{"id":1530,"date":"2012-12-12T21:41:30","date_gmt":"2012-12-12T21:41:30","guid":{"rendered":"http:\/\/hbsl.ch\/1fsLlFB"},"modified":"2014-03-15T17:37:23","modified_gmt":"2014-03-15T15:37:23","slug":"bei-getr-nkedosen-auf-die-seite-und-nicht-oben","status":"publish","type":"post","link":"https:\/\/humanoids.be\/log\/2012\/12\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\/","title":{"rendered":"Dosen sicher \u00f6ffnen"},"content":{"rendered":"<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><\/p>\n<div class=\"embed-privacy-container is-disabled embed-youtube\" data-embed-id=\"oembed_7c140c9460b3919247573f5263316ac9\" data-embed-provider=\"youtube\" style=\"aspect-ratio: 2560\/1440;\">\t\t\t\t\t\t<button type=\"button\" class=\"embed-privacy-enable screen-reader-text\">Display content from YouTube<\/button>\t\t\t\t\t\t<\/p>\n<div class=\"embed-privacy-overlay\">\n<div class=\"embed-privacy-inner\">\n<div class=\"embed-privacy-logo\" style=\"background-image: url(https:\/\/humanoids.be\/log\/wp-content\/plugins\/embed-privacy\/assets\/images\/embed-youtube.png?ver=1.12.3);\"><\/div>\n<p>\t\tClick here to display content from YouTube.\t\t\t\t\t<br \/>\t\t\t\t\tLearn more in <a href=\"https:\/\/policies.google.com\/privacy?hl=en\" target=\"_blank\">YouTube\u2019s privacy policy<\/a>.\t\t<\/p>\n<p class=\"embed-privacy-input-wrapper\">\t\t\t<input id=\"embed-privacy-store-youtube-7c140c9460b3919247573f5263316ac9\" type=\"checkbox\" value=\"1\" class=\"embed-privacy-input\" data-embed-provider=\"youtube\">\t\t\t<label for=\"embed-privacy-store-youtube-7c140c9460b3919247573f5263316ac9\" class=\"embed-privacy-label\" data-embed-provider=\"youtube\">\t\t\t\tAlways display content from YouTube\t\t\t<\/label>\t\t<\/p>\n<\/p><\/div>\n<div class=\"embed-privacy-footer\"><span class=\"embed-privacy-url\"><a href=\"https:\/\/www.youtube.com\/embed\/l5xbgNTxApo?version=3&amp;rel=1&amp;showsearch=0&amp;showinfo=1&amp;iv_load_policy=1&amp;fs=1&amp;hl=en-US&amp;autohide=2&amp;wmode=transparent\">Open video directly<\/a><\/span><\/div>\n<\/p><\/div>\n<div class=\"embed-privacy-content\">\t\t\t\t<script>var _oembed_7c140c9460b3919247573f5263316ac9 = '{\\\"embed\\\":\\\"&lt;iframe class=&quot;youtube-player&quot; width=&quot;2560&quot; height=&quot;1440&quot; src=&quot;https:\\\\\/\\\\\/www.youtube-nocookie.com\\\\\/embed\\\\\/l5xbgNTxApo?version=3&amp;amp;rel=1&amp;amp;showsearch=0&amp;amp;showinfo=1&amp;amp;iv_load_policy=1&amp;amp;fs=1&amp;amp;hl=en-US&amp;amp;autohide=2&amp;amp;wmode=transparent&quot; allowfullscreen=&quot;true&quot; style=&quot;border:0;&quot; sandbox=&quot;allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox&quot;&gt;&lt;\\\\\/iframe&gt;\\\"}';<\/script>\t\t\t<\/div>\n<\/p><\/div>\n<p><\/span><\/p>\n<p>Bei Getr\u00e4nkedosen auf die Seite und nicht oben drauf klopfen!<\/p>\n<p>Soda Can Shake-Up (von <a href=\"http:\/\/www.youtube.com\/watch?v=l5xbgNTxApo&amp;feature=share\" target=\"_blank\">SteveSpanglerScience<\/a>)\n<\/p>\n<div class=\"attribution\">(Source: <a href=\"http:\/\/www.youtube.com\/\">http:\/\/www.youtube.com\/<\/a>)<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Display content from YouTube Click here to display content from YouTube. Learn more in YouTube\u2019s privacy policy. Always display content from YouTube Open video directly Bei Getr\u00e4nkedosen auf die Seite und nicht oben drauf klopfen! Soda Can Shake-Up (von SteveSpanglerScience) (Source: http:\/\/www.youtube.com\/)<\/p>\n","protected":false},"author":2,"featured_media":1531,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[5],"tags":[258,259],"class_list":["post-1530","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-alltag","tag-science","tag-soda-can","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dosen sicher \u00f6ffnen - Humanoids beLog<\/title>\n<meta name=\"description\" content=\"http:\/\/www.youtube.com\/watch?v=l5xbgNTxApo Bei Getr\u00e4nkedosen auf die Seite und nicht oben drauf klopfen! Soda Can Shake-Up (von SteveSpanglerScience)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/humanoids.be\/log\/2012\/12\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dosen sicher \u00f6ffnen - Humanoids beLog\" \/>\n<meta property=\"og:description\" content=\"http:\/\/www.youtube.com\/watch?v=l5xbgNTxApo Bei Getr\u00e4nkedosen auf die Seite und nicht oben drauf klopfen! Soda Can Shake-Up (von SteveSpanglerScience)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/humanoids.be\/log\/2012\/12\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\/\" \/>\n<meta property=\"og:site_name\" content=\"Humanoids beLog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/humanoidsbelog\" \/>\n<meta property=\"article:published_time\" content=\"2012-12-12T21:41:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-03-15T15:37:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/humanoids.be\/log\/wp-content\/uploads\/2014\/01\/1530.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin Giger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@freaktechnik\" \/>\n<meta name=\"twitter:site\" content=\"@freaktechnik\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Giger\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/humanoids.be\\\/log\\\/2012\\\/12\\\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/humanoids.be\\\/log\\\/2012\\\/12\\\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\\\/\"},\"author\":{\"name\":\"Martin Giger\",\"@id\":\"https:\\\/\\\/humanoids.be\\\/log\\\/#\\\/schema\\\/person\\\/a58850edf3908fc1b0987aedfb9a080d\"},\"headline\":\"Dosen sicher \u00f6ffnen\",\"datePublished\":\"2012-12-12T21:41:30+00:00\",\"dateModified\":\"2014-03-15T15:37:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/humanoids.be\\\/log\\\/2012\\\/12\\\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\\\/\"},\"wordCount\":32,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/humanoids.be\\\/log\\\/2012\\\/12\\\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/humanoids.be\\\/log\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/1530.jpg\",\"keywords\":[\"science\",\"soda can\"],\"articleSection\":[\"Alltag\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/humanoids.be\\\/log\\\/2012\\\/12\\\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/humanoids.be\\\/log\\\/2012\\\/12\\\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\\\/\",\"url\":\"https:\\\/\\\/humanoids.be\\\/log\\\/2012\\\/12\\\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\\\/\",\"name\":\"Dosen sicher \u00f6ffnen - Humanoids beLog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/humanoids.be\\\/log\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/humanoids.be\\\/log\\\/2012\\\/12\\\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/humanoids.be\\\/log\\\/2012\\\/12\\\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/humanoids.be\\\/log\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/1530.jpg\",\"datePublished\":\"2012-12-12T21:41:30+00:00\",\"dateModified\":\"2014-03-15T15:37:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/humanoids.be\\\/log\\\/#\\\/schema\\\/person\\\/a58850edf3908fc1b0987aedfb9a080d\"},\"description\":\"http:\\\/\\\/www.youtube.com\\\/watch?v=l5xbgNTxApo Bei Getr\u00e4nkedosen auf die Seite und nicht oben drauf klopfen! Soda Can Shake-Up (von SteveSpanglerScience)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/humanoids.be\\\/log\\\/2012\\\/12\\\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/humanoids.be\\\/log\\\/2012\\\/12\\\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/humanoids.be\\\/log\\\/2012\\\/12\\\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\\\/#primaryimage\",\"url\":\"https:\\\/\\\/humanoids.be\\\/log\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/1530.jpg\",\"contentUrl\":\"https:\\\/\\\/humanoids.be\\\/log\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/1530.jpg\",\"width\":480,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/humanoids.be\\\/log\\\/2012\\\/12\\\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/humanoids.be\\\/log\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dosen sicher \u00f6ffnen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/humanoids.be\\\/log\\\/#website\",\"url\":\"https:\\\/\\\/humanoids.be\\\/log\\\/\",\"name\":\"Humanoids beLog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/humanoids.be\\\/log\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/humanoids.be\\\/log\\\/#\\\/schema\\\/person\\\/a58850edf3908fc1b0987aedfb9a080d\",\"name\":\"Martin Giger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8766da02c6809c8ca3142c0c75bbfd454a6d1120dc01fede05d0beffedb6dd40?s=96&d=mm&r=pg\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8766da02c6809c8ca3142c0c75bbfd454a6d1120dc01fede05d0beffedb6dd40?s=96&d=mm&r=pg\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8766da02c6809c8ca3142c0c75bbfd454a6d1120dc01fede05d0beffedb6dd40?s=96&d=mm&r=pg\",\"caption\":\"Martin Giger\"},\"description\":\"openpgp4fpr:89346D522A2C190EEB959F52AE530058EFE7FD60\",\"sameAs\":[\"http:\\\/\\\/humanoids.be\\\/\"],\"url\":\"https:\\\/\\\/humanoids.be\\\/log\\\/author\\\/humanoid\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dosen sicher \u00f6ffnen - Humanoids beLog","description":"http:\/\/www.youtube.com\/watch?v=l5xbgNTxApo Bei Getr\u00e4nkedosen auf die Seite und nicht oben drauf klopfen! Soda Can Shake-Up (von SteveSpanglerScience)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/humanoids.be\/log\/2012\/12\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\/","og_locale":"en_US","og_type":"article","og_title":"Dosen sicher \u00f6ffnen - Humanoids beLog","og_description":"http:\/\/www.youtube.com\/watch?v=l5xbgNTxApo Bei Getr\u00e4nkedosen auf die Seite und nicht oben drauf klopfen! Soda Can Shake-Up (von SteveSpanglerScience)","og_url":"https:\/\/humanoids.be\/log\/2012\/12\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\/","og_site_name":"Humanoids beLog","article_publisher":"https:\/\/www.facebook.com\/humanoidsbelog","article_published_time":"2012-12-12T21:41:30+00:00","article_modified_time":"2014-03-15T15:37:23+00:00","og_image":[{"width":480,"height":360,"url":"https:\/\/humanoids.be\/log\/wp-content\/uploads\/2014\/01\/1530.jpg","type":"image\/jpeg"}],"author":"Martin Giger","twitter_card":"summary_large_image","twitter_creator":"@freaktechnik","twitter_site":"@freaktechnik","twitter_misc":{"Written by":"Martin Giger"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/humanoids.be\/log\/2012\/12\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\/#article","isPartOf":{"@id":"https:\/\/humanoids.be\/log\/2012\/12\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\/"},"author":{"name":"Martin Giger","@id":"https:\/\/humanoids.be\/log\/#\/schema\/person\/a58850edf3908fc1b0987aedfb9a080d"},"headline":"Dosen sicher \u00f6ffnen","datePublished":"2012-12-12T21:41:30+00:00","dateModified":"2014-03-15T15:37:23+00:00","mainEntityOfPage":{"@id":"https:\/\/humanoids.be\/log\/2012\/12\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\/"},"wordCount":32,"commentCount":0,"image":{"@id":"https:\/\/humanoids.be\/log\/2012\/12\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\/#primaryimage"},"thumbnailUrl":"https:\/\/humanoids.be\/log\/wp-content\/uploads\/2014\/01\/1530.jpg","keywords":["science","soda can"],"articleSection":["Alltag"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/humanoids.be\/log\/2012\/12\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/humanoids.be\/log\/2012\/12\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\/","url":"https:\/\/humanoids.be\/log\/2012\/12\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\/","name":"Dosen sicher \u00f6ffnen - Humanoids beLog","isPartOf":{"@id":"https:\/\/humanoids.be\/log\/#website"},"primaryImageOfPage":{"@id":"https:\/\/humanoids.be\/log\/2012\/12\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\/#primaryimage"},"image":{"@id":"https:\/\/humanoids.be\/log\/2012\/12\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\/#primaryimage"},"thumbnailUrl":"https:\/\/humanoids.be\/log\/wp-content\/uploads\/2014\/01\/1530.jpg","datePublished":"2012-12-12T21:41:30+00:00","dateModified":"2014-03-15T15:37:23+00:00","author":{"@id":"https:\/\/humanoids.be\/log\/#\/schema\/person\/a58850edf3908fc1b0987aedfb9a080d"},"description":"http:\/\/www.youtube.com\/watch?v=l5xbgNTxApo Bei Getr\u00e4nkedosen auf die Seite und nicht oben drauf klopfen! Soda Can Shake-Up (von SteveSpanglerScience)","breadcrumb":{"@id":"https:\/\/humanoids.be\/log\/2012\/12\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/humanoids.be\/log\/2012\/12\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/humanoids.be\/log\/2012\/12\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\/#primaryimage","url":"https:\/\/humanoids.be\/log\/wp-content\/uploads\/2014\/01\/1530.jpg","contentUrl":"https:\/\/humanoids.be\/log\/wp-content\/uploads\/2014\/01\/1530.jpg","width":480,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/humanoids.be\/log\/2012\/12\/bei-getr-nkedosen-auf-die-seite-und-nicht-oben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/humanoids.be\/log\/"},{"@type":"ListItem","position":2,"name":"Dosen sicher \u00f6ffnen"}]},{"@type":"WebSite","@id":"https:\/\/humanoids.be\/log\/#website","url":"https:\/\/humanoids.be\/log\/","name":"Humanoids beLog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/humanoids.be\/log\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/humanoids.be\/log\/#\/schema\/person\/a58850edf3908fc1b0987aedfb9a080d","name":"Martin Giger","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8766da02c6809c8ca3142c0c75bbfd454a6d1120dc01fede05d0beffedb6dd40?s=96&d=mm&r=pg","url":"https:\/\/secure.gravatar.com\/avatar\/8766da02c6809c8ca3142c0c75bbfd454a6d1120dc01fede05d0beffedb6dd40?s=96&d=mm&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8766da02c6809c8ca3142c0c75bbfd454a6d1120dc01fede05d0beffedb6dd40?s=96&d=mm&r=pg","caption":"Martin Giger"},"description":"openpgp4fpr:89346D522A2C190EEB959F52AE530058EFE7FD60","sameAs":["http:\/\/humanoids.be\/"],"url":"https:\/\/humanoids.be\/log\/author\/humanoid\/"}]}},"jetpack_featured_media_url":"https:\/\/humanoids.be\/log\/wp-content\/uploads\/2014\/01\/1530.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/humanoids.be\/log\/wp-json\/wp\/v2\/posts\/1530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/humanoids.be\/log\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/humanoids.be\/log\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/humanoids.be\/log\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/humanoids.be\/log\/wp-json\/wp\/v2\/comments?post=1530"}],"version-history":[{"count":3,"href":"https:\/\/humanoids.be\/log\/wp-json\/wp\/v2\/posts\/1530\/revisions"}],"predecessor-version":[{"id":2310,"href":"https:\/\/humanoids.be\/log\/wp-json\/wp\/v2\/posts\/1530\/revisions\/2310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/humanoids.be\/log\/wp-json\/wp\/v2\/media\/1531"}],"wp:attachment":[{"href":"https:\/\/humanoids.be\/log\/wp-json\/wp\/v2\/media?parent=1530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/humanoids.be\/log\/wp-json\/wp\/v2\/categories?post=1530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/humanoids.be\/log\/wp-json\/wp\/v2\/tags?post=1530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}